{"id":529,"date":"2019-08-29T21:25:25","date_gmt":"2019-08-30T00:25:25","guid":{"rendered":"http:\/\/itr.ufrrj.br\/pet\/?p=529"},"modified":"2019-08-29T21:29:19","modified_gmt":"2019-08-30T00:29:19","slug":"529","status":"publish","type":"post","link":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/","title":{"rendered":"O que \u00e9 MP da Liberdade Econ\u00f4mica?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-530 aligncenter\" src=\"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg\" alt=\"\" width=\"596\" height=\"220\" srcset=\"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg 300w, http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-768x284.jpg 768w, http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-1024x379.jpg 1024w, http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia.jpg 1080w, http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-810x300.jpg 810w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/p>\n<p style=\"text-align: left;\">\u00a0 \u00a0 Na noite do dia 21 de agosto foi aprovada a Medida Provis\u00f3ria (MP) da Liberdade<br \/>\nEcon\u00f4mica pelo Senado. A \u00fanica restri\u00e7\u00e3o foi em rela\u00e7\u00e3o a parte que mudava regras de<br \/>\ntrabalho nos domingos e feriados. Pol\u00eamica, alvo de elogios e cr\u00edticas, o projeto visa<br \/>\nreduzir as interven\u00e7\u00f5es reguladoras do Estado, seja na obten\u00e7\u00e3o de licen\u00e7as para exercer<br \/>\ndeterminadas atividades consideradas \u201cde baixo risco\u201d ou na fiscaliza\u00e7\u00e3o e regulamenta\u00e7\u00e3o<br \/>\ndas rela\u00e7\u00f5es trabalhistas. O intuito \u00e9 impulsionar o aquecimento da economia brasileira<br \/>\ngerando empregos e, consequentemente, aumentando o bem-estar geral da popula\u00e7\u00e3o.<br \/>\n\u201c\u00c9 um texto que vai gerar impacto muito grande para a economia. Mais de 3,7<br \/>\nmilh\u00f5es de empregos, mais de 7% no crescimento do PIB\u201d. S\u00e3o n\u00fameros<br \/>\nimportantes, necess\u00e1rios, que v\u00e3o ajudar a retomada da economia no Brasil\u201d, afirma<br \/>\nPaulo Uebel, secret\u00e1rio especial de Desburocratiza\u00e7\u00e3o do Minist\u00e9rio da Economia.<br \/>\nAlgumas mudan\u00e7as da nova MP:<br \/>\n.Registro dos hor\u00e1rios de entrada e sa\u00edda do trabalho passa a ser obrigat\u00f3rio somente para<br \/>\nempresas com mais de 20 funcion\u00e1rios, contra m\u00ednimo de 10 empregados atualmente<br \/>\n.Trabalho fora do estabelecimento dever\u00e1 ser registrado.<br \/>\nPrincipais artigos da nova MP da Liberdade econ\u00f4mica:<br \/>\n-Art. 3\u00ba, inciso I Fim de atos de libera\u00e7\u00e3o para atividades de baixo risco<br \/>\n.Agora as atividades de baixo risco n\u00e3o precisar\u00e3o de libera\u00e7\u00e3o pr\u00e9via para gerar emprego<br \/>\ne renda.<br \/>\n-Art. 3\u00ba, inciso II Liberdade de hor\u00e1rio e dia para gerar emprego e renda<br \/>\n.As restri\u00e7\u00f5es de hor\u00e1rios para atividades econ\u00f4micas dever\u00e3o ser justificadas, caso<br \/>\ncontr\u00e1rio a regra \u00e9 a flexibilidade para melhor atender o consumidor<br \/>\n-Art. 3\u00ba, inciso III Pre\u00e7os devem refletir oferta e demanda<br \/>\n.Ser\u00e1 garantida a liberdade de fixar e flutuar pre\u00e7os, como consequ\u00eancia da oferta e<br \/>\ndemanda do mercado, observada a legisla\u00e7\u00e3o trabalhista<br \/>\n-Art. 3\u00ba, inciso IV Decis\u00f5es administrativas igualit\u00e1rias, sem discrimina\u00e7\u00e3o<br \/>\n.Se presentes as mesma circunst\u00e2ncias, o \u00f3rg\u00e3o deve agir de maneira id\u00eantica, vinculando<br \/>\nsuas interpreta\u00e7\u00f5es e decis\u00f5es passadas. O que for decidido para uma pessoa dever\u00e1 valer<br \/>\npara todos<br \/>\n-Art. 3\u00ba, inciso VII Desburocratiza o processo de inova\u00e7\u00e3o e novos modelos de neg\u00f3cios<br \/>\n.Enquanto exercido dentro dos crit\u00e9rios da Medida, ser\u00e1 livre de burocracia a inova\u00e7\u00e3o no<br \/>\nBrasil<br \/>\n-Art. 3\u00ba, inciso VIII Respeito aos contratos empresariais entre as partes privadas<br \/>\n.Entre as partes, o contrato empresarial dever\u00e1 ser respeitado, havendo grandes incentivos<br \/>\nde seguran\u00e7a jur\u00eddica e alinhamento \u00e0s melhores pr\u00e1ticas internacionais, em que o<br \/>\npactuado entre as partes entre elas, tem for\u00e7a de lei<br \/>\n-Art. 3\u00ba, inciso VIII Fim do Papel e Brasil Digital<br \/>\n.O particular poder\u00e1, ap\u00f3s a regulamenta\u00e7\u00e3o, digitalizar documentos e descartar o original,<br \/>\nsendo mais seguro, econ\u00f4mico e sustent\u00e1vel; al\u00e9m de facilitar a transmiss\u00e3o e fiscaliza\u00e7\u00e3o<br \/>\ndas atividades.<br \/>\nDentre as cr\u00edticas a aprova\u00e7\u00e3o da MP, h\u00e1 a do secret\u00e1rio de assuntos jur\u00eddicos da central<br \/>\n\u00fanica dos trabalhadores (CUT). Ele declarou ser a favor de pol\u00edticas que visem<br \/>\ndesburocratizar as empresas, mas, segundo ele, as coloca\u00e7\u00f5es expressas na proposta<br \/>\ntrar\u00e3o selvageria ao mercado.<br \/>\n\u2014 \u201c \u00c9 um absurdo a discuss\u00e3o da liberdade econ\u00f4mica em cima do lombo dos<br \/>\ntrabalhadores \u201c<br \/>\nFonte: Ag\u00eancia Senado<\/p>\n<p>\u00a0 \u00a0 Para o procurador do trabalho M\u00e1rcio Amazonas Cabral de Andrade como uma tentativa<br \/>\ntrai\u00e7oeira de impor uma nova reforma trabalhista disfar\u00e7ada, atacando institui\u00e7\u00f5es que<br \/>\ndeveriam ser independentes em rela\u00e7\u00e3o ao governo como, por exemplo, o Minist\u00e9rio do<br \/>\nTrabalho.<br \/>\nSegundo ele, \u2014 Ainda n\u00e3o temos no\u00e7\u00e3o dos impactos positivos e negativos da primeira<br \/>\nreforma trabalhista, e estamos emendando uma reforma at\u00e9 mais grave \u2014<\/p>\n<p style=\"text-align: right;\">Fonte: Ag\u00eancia Senado<\/p>\n<p>\u00a0 \u00a0 Em defesa, sendo homenageado pela Federa\u00e7\u00e3o das Ind\u00fastrias do Rio de Janeiro<br \/>\n(FIRJAN), Bolsonaro, em um breve discurso, disse que os empres\u00e1rios brasileiros s\u00e3o<br \/>\nher\u00f3is e que far\u00e1 o poss\u00edvel para que o Estado \u201catrapalhe\u201d cada vez menos as rela\u00e7\u00f5es de<br \/>\nmercado brasileiras. Influenciado pelas ideias liberais de seu ministro da economia, Jair<br \/>\nMessias Bolsonaro parece querer reproduzir tra\u00e7os da personalidade pol\u00edtica de l\u00edderes<br \/>\ncomo Reagan, Tatcher e Trump. Seu \u00edmpeto por representar bandeiras correlacionadas a<br \/>\ndireita brasileira faz com que, em seu discurso, defenda a interfer\u00eancia m\u00ednima do Estado<br \/>\nnas rela\u00e7\u00f5es econ\u00f4micas e, ao mesmo tempo, a n\u00e3o interven\u00e7\u00e3o deste no \u00e2mbito familiar,<br \/>\nou seja, a avers\u00e3o a toda e qualquer pol\u00edtica que busque processos de engenharia social.<br \/>\nH\u00e1 uma busca desenfreada da oposi\u00e7\u00e3o pol\u00edtica em denegrir a imagem do atual governo<br \/>\ncorrelaciona as a\u00e7\u00f5es em que encontram \u201cbrechas\u201d com a velha tese da opress\u00e3o ao<br \/>\nproletariado em prol da satisfa\u00e7\u00e3o de uma elite capitalista representada pelo setor privado.<br \/>\nEm contrapartida, a direita se favoreceu da insatisfa\u00e7\u00e3o popular proveniente dos impactos<br \/>\nda crise econ\u00f4mica mundial e dos esc\u00e2ndalos de corrup\u00e7\u00e3o para resgatar o velho<br \/>\nespantalho atacado pela classe m\u00e9dia desde meados do regime militar: uma conspira\u00e7\u00e3o<br \/>\ncomunista.<br \/>\nPor fim, a situa\u00e7\u00e3o atual do brasil se resume a um conflito acirrado entre dois polos pol\u00edticos<br \/>\nque re\u00fanem diferentes vertentes ideol\u00f3gicas as quais se uniram a partir de assimila\u00e7\u00f5es<br \/>\nentre si. Quando um pol\u00edtico conhecido por defender determinado conjunto do eleitorado<br \/>\nsobe ao p\u00falpito, geralmente n\u00e3o est\u00e1 preocupado com encontrar a verdade da polis a partir<br \/>\ndo contraste entre argumentos dissociados, mas com expressar aquilo que sua comunidade<br \/>\npol\u00edtica quer ouvir. Isso significa que, infelizmente, n\u00e3o h\u00e1 um debate em busca de<br \/>\nconsenso s\u00f3brio sobre determinada quest\u00e3o em favor do bem-estar geral da comunidade, e<br \/>\nsim a reafirma\u00e7\u00e3o de uma verdade pr\u00e9-estabelecida e defendida por seus semelhantes.<\/p>\n<p>Fontes:<br \/>\nhttps:\/\/economia.uol.com.br\/noticias\/redacao\/2019\/08\/22\/entenda-as-principais-mudancas-da-mp-da-liberdade-e<br \/>\nconomica.htm (acessado em 28\/08\/19 \u00e0s 15:03)<br \/>\nhttps:\/\/www12.senado.leg.br\/noticias\/materias\/2019\/08\/13\/mp-da-liberdade-economica-tira-direitos-dos-trabalhad<br \/>\nores-dizem-debatedores (acessado em 29\/08\/19 \u00e0s 16:01)<br \/>\nhttps:\/\/g1.globo.com\/jornal-nacional\/noticia\/2019\/08\/22\/mp-da-liberdade-economica-e-aprovada-e-vai-a-sancaode-bolsonaro.ghtml (acessado em 29\/08\/19 \u00e0s 15:45)<br \/>\nhttps:\/\/www.congressonacional.leg.br\/materias\/medidas-provisorias\/-\/mpv\/136531<\/p>\n<p style=\"text-align: right;\">Por Lucas e Thiago<\/p>\n<h4><em>Bem-vindos a Coluna PET. Teremos posts semanais multidisciplinares, para voc\u00ea se manter atualizado e conhecer um pouco mais sobre diversos assuntos. Fiquem ligados, os posts ser\u00e3o as quintas.<\/em><\/h4>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 Na noite do dia 21 de agosto foi aprovada a Medida Provis\u00f3ria (MP) da Liberdade Econ\u00f4mica pelo Senado. A \u00fanica restri\u00e7\u00e3o foi em rela\u00e7\u00e3o a parte que mudava regras de trabalho nos domingos e feriados. Pol\u00eamica, alvo de<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-529","post","type-post","status-publish","format-standard","hentry","category-coluna-pet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u00a0 Na noite do dia 21 de agosto foi aprovada a Medida Provis\u00f3ria (MP) da Liberdade Econ\u00f4mica pelo Senado. A \u00fanica restri\u00e7\u00e3o foi em rela\u00e7\u00e3o a parte que mudava regras de trabalho nos domingos e feriados. Pol\u00eamica, alvo de\" \/>\n<meta property=\"og:url\" content=\"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/\" \/>\n<meta property=\"og:site_name\" content=\"PET Conex\u00f5es de Saberes\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-30T00:25:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-30T00:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg\" \/>\n<meta name=\"author\" content=\"Equipe PET\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe PET\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/\"},\"author\":{\"name\":\"Equipe PET\",\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#\\\/schema\\\/person\\\/4fc6b6ce7db89726fb5e1583394291fd\"},\"headline\":\"O que \u00e9 MP da Liberdade Econ\u00f4mica?\",\"datePublished\":\"2019-08-30T00:25:25+00:00\",\"dateModified\":\"2019-08-30T00:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/\"},\"wordCount\":1062,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/economia-300x111.jpg\",\"articleSection\":[\"Coluna PET\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/\",\"url\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/\",\"name\":\"O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/economia-300x111.jpg\",\"datePublished\":\"2019-08-30T00:25:25+00:00\",\"dateModified\":\"2019-08-30T00:29:19+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#primaryimage\",\"url\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/economia.jpg\",\"contentUrl\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/economia.jpg\",\"width\":1080,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/2019\\\/08\\\/29\\\/529\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 MP da Liberdade Econ\u00f4mica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#website\",\"url\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/\",\"name\":\"PET Conex\u00f5es de Saberes\",\"description\":\"Campus Tr\u00eas Rios - UFRRJ\",\"publisher\":{\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#organization\",\"name\":\"PET Conex\u00f5es de Saberes\",\"url\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-LOGO.PETNOVA-5.png\",\"contentUrl\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-LOGO.PETNOVA-5.png\",\"width\":416,\"height\":376,\"caption\":\"PET Conex\u00f5es de Saberes\"},\"image\":{\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itr.ufrrj.br\\\/pet\\\/#\\\/schema\\\/person\\\/4fc6b6ce7db89726fb5e1583394291fd\",\"name\":\"Equipe PET\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g\",\"caption\":\"Equipe PET\"},\"url\":\"http:\\\/\\\/itr.ufrrj.br\\\/pet\\\/author\\\/jully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes","og_description":"\u00a0 \u00a0 Na noite do dia 21 de agosto foi aprovada a Medida Provis\u00f3ria (MP) da Liberdade Econ\u00f4mica pelo Senado. A \u00fanica restri\u00e7\u00e3o foi em rela\u00e7\u00e3o a parte que mudava regras de trabalho nos domingos e feriados. Pol\u00eamica, alvo de","og_url":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/","og_site_name":"PET Conex\u00f5es de Saberes","article_published_time":"2019-08-30T00:25:25+00:00","article_modified_time":"2019-08-30T00:29:19+00:00","og_image":[{"url":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg","type":"","width":"","height":""}],"author":"Equipe PET","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe PET","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#article","isPartOf":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/"},"author":{"name":"Equipe PET","@id":"https:\/\/itr.ufrrj.br\/pet\/#\/schema\/person\/4fc6b6ce7db89726fb5e1583394291fd"},"headline":"O que \u00e9 MP da Liberdade Econ\u00f4mica?","datePublished":"2019-08-30T00:25:25+00:00","dateModified":"2019-08-30T00:29:19+00:00","mainEntityOfPage":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/"},"wordCount":1062,"commentCount":0,"publisher":{"@id":"https:\/\/itr.ufrrj.br\/pet\/#organization"},"image":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#primaryimage"},"thumbnailUrl":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg","articleSection":["Coluna PET"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/","url":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/","name":"O que \u00e9 MP da Liberdade Econ\u00f4mica? - PET Conex\u00f5es de Saberes","isPartOf":{"@id":"https:\/\/itr.ufrrj.br\/pet\/#website"},"primaryImageOfPage":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#primaryimage"},"image":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#primaryimage"},"thumbnailUrl":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia-300x111.jpg","datePublished":"2019-08-30T00:25:25+00:00","dateModified":"2019-08-30T00:29:19+00:00","breadcrumb":{"@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#primaryimage","url":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia.jpg","contentUrl":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2019\/08\/economia.jpg","width":1080,"height":400},{"@type":"BreadcrumbList","@id":"http:\/\/itr.ufrrj.br\/pet\/2019\/08\/29\/529\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itr.ufrrj.br\/pet\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 MP da Liberdade Econ\u00f4mica?"}]},{"@type":"WebSite","@id":"https:\/\/itr.ufrrj.br\/pet\/#website","url":"https:\/\/itr.ufrrj.br\/pet\/","name":"PET Conex\u00f5es de Saberes","description":"Campus Tr\u00eas Rios - UFRRJ","publisher":{"@id":"https:\/\/itr.ufrrj.br\/pet\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itr.ufrrj.br\/pet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/itr.ufrrj.br\/pet\/#organization","name":"PET Conex\u00f5es de Saberes","url":"https:\/\/itr.ufrrj.br\/pet\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/itr.ufrrj.br\/pet\/#\/schema\/logo\/image\/","url":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2020\/07\/cropped-LOGO.PETNOVA-5.png","contentUrl":"http:\/\/itr.ufrrj.br\/pet\/wp-content\/uploads\/2020\/07\/cropped-LOGO.PETNOVA-5.png","width":416,"height":376,"caption":"PET Conex\u00f5es de Saberes"},"image":{"@id":"https:\/\/itr.ufrrj.br\/pet\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/itr.ufrrj.br\/pet\/#\/schema\/person\/4fc6b6ce7db89726fb5e1583394291fd","name":"Equipe PET","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fff511ccb50de5cccc7ca8bf996110a708763bfa5e0017c6670d467e6046b2c7?s=96&d=mm&r=g","caption":"Equipe PET"},"url":"http:\/\/itr.ufrrj.br\/pet\/author\/jully\/"}]}},"_links":{"self":[{"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/posts\/529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/comments?post=529"}],"version-history":[{"count":3,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/posts\/529\/revisions"}],"predecessor-version":[{"id":537,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/posts\/529\/revisions\/537"}],"wp:attachment":[{"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/media?parent=529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/categories?post=529"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/itr.ufrrj.br\/pet\/wp-json\/wp\/v2\/tags?post=529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}